{"id":6171,"date":"2024-03-22T11:24:04","date_gmt":"2024-03-22T10:24:04","guid":{"rendered":"https:\/\/www.bordeaux-population-health.center\/?p=6171"},"modified":"2024-03-22T12:15:26","modified_gmt":"2024-03-22T11:15:26","slug":"press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries","status":"publish","type":"post","link":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/","title":{"rendered":"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatrique<br \/>vers les h\u00f4pitaux de district et les centres de sant\u00e9 primaire<br \/>dans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es"},"content":{"rendered":"<div style=\"font-family: arial; font-size: 1.1em;\">\n<p><img decoding=\"async\" class=\"size-medium wp-image-2266 alignright\" style=\"margin-left: 10%; width: 80%;\" src=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed_decentralization_study_bandeau.jpg\" alt=\"\" \/><\/p>\n<p><strong style=\"display: block; text-align: center; font-size: 1.2em; margin-top: 2em;\">D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatrique<br \/>vers les h\u00f4pitaux de district et les centres de sant\u00e9 primaire<br \/>dans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es<\/strong><\/p>\n<div style=\"margin-left: 10%; width: 80%; margin-top: 3em;\">\n<p><strong><br \/>\nDeux \u00e9valuations issues d&rsquo;une \u00e9tude portant sur la d\u00e9centralisation du diagnostic de la tuberculose de l\u2019enfant dans les h\u00f4pitaux de district et les centres de sant\u00e9 primaire viennent d&rsquo;\u00eatre publi\u00e9es dans le journal eClinicalMedicine. L&rsquo;\u00e9tude a \u00e9t\u00e9 men\u00e9e dans six pays \u00e0 forte incidence de tuberculose (Cambodge, Cameroun, C\u00f4te d&rsquo;Ivoire, Mozambique, Sierra Leone et Ouganda) dans le cadre du projet TB-Speed mis en oeuvre par l&rsquo;Institut Pasteur (Cambodge), l&rsquo;IRD (Cameroun), PACCI (C\u00f4te d&rsquo;Ivoire), l&rsquo;Instituto Nacional de Saude (Mozambique), Soltis (Sierra Leone), MU-JHU (Ouganda) et coordonn\u00e9 par l&rsquo;Universit\u00e9 de Bordeaux (France).<br \/>\n<\/strong><\/p>\n<p style=\"margin-top: 2em;\">La premi\u00e8re publication, dirig\u00e9e par l&rsquo;Institut de recherche ougandais <a href=\"https:\/\/www.mujhu.org\/\" rel=\"noopener\" target=\"_blank\">MU-JHU<\/a> (une collaboration de recherche en Ouganda entre l&rsquo;universit\u00e9 Makerere et l&rsquo;universit\u00e9 John Hopkins), l&rsquo;Institut de recherche pour le d\u00e9veloppement (<a href=\"https:\/\/en.ird.fr\/\" rel=\"noopener\" target=\"_blank\">IRD<\/a>) et l&rsquo;<a href=\"https:\/\/www.u-bordeaux.fr\" rel=\"noopener\" target=\"_blank\">universit\u00e9 de Bordeaux<\/a>, \u00e9value l&rsquo;effet de la d\u00e9centralisation du diagnostic de la tuberculose de l\u2019enfant dans les h\u00f4pitaux de district et les centres de sant\u00e9 primaires. La seconde publication, dirig\u00e9e par l&rsquo;<a href=\"https:\/\/www.sheffield.ac.uk\/\" rel=\"noopener\" target=\"_blank\">universit\u00e9 de Sheffield<\/a> (Royaume-Uni) et l&rsquo;universit\u00e9 de Bordeaux, \u00e9value le rapport co\u00fbt-efficacit\u00e9 et l&rsquo;impact budg\u00e9taire de cette d\u00e9centralisation.<\/p>\n<p style=\"margin-top: 2em; margin-left: 10%; width: 80%;\">La tuberculose touche plus d&rsquo;un million d&rsquo;enfants chaque ann\u00e9e, mais moins de la moiti\u00e9 d&rsquo;entre eux sont diagnostiqu\u00e9s et trait\u00e9s. Ce sous-diagnostic est \u00e0 l&rsquo;origine de plus de 200 000 d\u00e9c\u00e8s chaque ann\u00e9e. Le diagnostic de la tuberculose est complexe chez les enfants, car il n\u00e9cessite des proc\u00e9dures sp\u00e9cifiques de pr\u00e9l\u00e8vement d&rsquo;\u00e9chantillons pour les tests, une expertise clinique et une bonne interpr\u00e9tation de la radiographie pulmonaire. Dans les pays \u00e0 ressources limit\u00e9es, ces capacit\u00e9s de diagnostic manquent aux niveaux p\u00e9riph\u00e9riques des services de sant\u00e9 dans lesquels la majorit\u00e9 des enfants viennent se faire soigner. En 2022, l&rsquo;Organisation Mondiale de la Sant\u00e9 a recommand\u00e9 la d\u00e9centralisation des services de lutte contre la tuberculose de l\u2019enfant afin d&rsquo;am\u00e9liorer l&rsquo;acc\u00e8s aux soins dans les centres de sant\u00e9 p\u00e9riph\u00e9riques.<\/p>\n<p style=\"margin-top: 2em;\">La faible d\u00e9tection de la tuberculose chez les enfants s&rsquo;explique en grande partie par leur difficult\u00e9 \u00e0 produire spontan\u00e9ment des expectorations et le faible rendement diagnostique des tests microbiologiques actuels, en raison de la nature paucibacillaire de la tuberculose chez les enfants. Un autre facteur important expliquant cette faible d\u00e9tection est li\u00e9 \u00e0 l\u2019organisation des syst\u00e8mes de sant\u00e9. Dans la majorit\u00e9 des pays \u00e0 forte incidence de tuberculose et aux ressources limit\u00e9es, les services de soins contre la tuberculose sont souvent centralis\u00e9s au niveau r\u00e9gional, inaccessibles pour la plupart des enfants. Les m\u00e9thodes de recueil d&rsquo;\u00e9chantillons respiratoires adapt\u00e9es aux enfants et les tests rapides de d\u00e9tection mol\u00e9culaire font souvent d\u00e9faut aux niveaux p\u00e9riph\u00e9riques des services de sant\u00e9. La radiographie pulmonaire, essentielle au diagnostic de la tuberculose non confirm\u00e9e microbiologiquement, n&rsquo;est disponible qu\u2019au niveau des h\u00f4pitaux de r\u00e9f\u00e9rence. Son utilisation est limit\u00e9e par la mauvaise qualit\u00e9 des radiographies et le manque de formation des cliniciens \u00e0 leur interpr\u00e9tation pour le diagnostic de la tuberculose de l\u2019enfant. Au niveau des centres de sant\u00e9 p\u00e9riph\u00e9riques, le personnel de sant\u00e9 est souvent peu sensibilis\u00e9 et peu enclin \u00e0 porter un diagnostic de tuberculose chez l\u2019enfant sans preuve microbiologique. Il existe jusqu&rsquo;\u00e0 pr\u00e9sent peu de donn\u00e9es sur pourquoi, comment et o\u00f9 d\u00e9centraliser ces services.<\/p>\n<p style=\"margin-top: 2em;\">\nLes progr\u00e8s r\u00e9cents dans le domaine diagnostique pourraient contribuer \u00e0 am\u00e9liorer le diagnostic de la tuberculose de l\u2019enfant au niveau des centres de sant\u00e9 p\u00e9riph\u00e9riques. La formation et le mentorat clinique pourraient aider les cliniciens \u00e0 la mise sous traitement sans confirmation microbiologique.\n<\/p>\n<div style=\"color: #ee9900; font-weight: bold; margin-top: 2em;\">+ d&rsquo;information sur les \u00e9tudes\/r\u00e9sultats<br \/>&#038; Acc\u00e8s au <a href=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed_Decentralization-Studies_Communique-presse_francais_VF.pdf\" rel=\"noopener\" target=\"_blank\">communiqu\u00e9 de presse<\/a><\/div>\n<p><a href=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed_Decentralization-Studies_Communique-presse_francais_VF.pdf\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" class=\"size-medium wp-image-2266 alignright\" style=\"margin-left: 30%; width: 40%; border: solid black 1px;\" src=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed_Decentralization-Studies_Communique-presse_francais_VF.jpg\" alt=\"\" \/><\/a><\/p>\n<div style=\"color: #ee9900; font-weight: bold; margin-top: 2em;\">Acc\u00e8s aux publications eClinicalMedicine<\/div>\n<p><a href=\"https:\/\/www.thelancet.com\/journals\/eclinm\/article\/PIIS2589-5370(24)00106-8\/fulltext\" rel=\"noopener\" target=\"_blank\">Effect of decentralizing childhood tuberculosis diagnosis to primary health center and district hospital level on disease detection in children from high tuberculosis incidence countries \u2013 An operational research with a pre-post study design<\/a><\/p>\n<p><a href=\"https:\/\/www.thelancet.com\/journals\/eclinm\/article\/PIIS2589-5370(24)00107-X\/fulltext\" rel=\"noopener\" target=\"_blank\">Cost-effectiveness and budget impact of decentralising childhood tuberculosis diagnosis in six high tuberculosis incidence countries: a mathematical modelling study<\/a><\/p>\n<div style=\"color: #ee9900; font-weight: bold; margin-top: 2em;\">Contact presse<\/div>\n<p><strong>IRD<\/strong> : Charlotte Gabet &#8211; presse@ird.fr <\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es Deux \u00e9valuations issues d&rsquo;une \u00e9tude portant sur la d\u00e9centralisation du diagnostic de la tuberculose de l\u2019enfant dans les h\u00f4pitaux de district et les centres de sant\u00e9 primaire [&hellip;]<\/p>\n","protected":false},"author":613,"featured_media":6157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-6171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-revue-de-presse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es | Bordeaux population health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es | Bordeaux population health\" \/>\n<meta property=\"og:description\" content=\"D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es Deux \u00e9valuations issues d&rsquo;une \u00e9tude portant sur la d\u00e9centralisation du diagnostic de la tuberculose de l\u2019enfant dans les h\u00f4pitaux de district et les centres de sant\u00e9 primaire [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/\" \/>\n<meta property=\"og:site_name\" content=\"Bordeaux population health\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-22T10:24:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T11:15:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed-Decentralization-Study_fr_vignette.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"819\" \/>\n\t<meta property=\"og:image:height\" content=\"443\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicolas Koskas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas Koskas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/\"},\"author\":{\"name\":\"Nicolas Koskas\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/f2fdc07742e044bb0a3193dc1f103183\"},\"headline\":\"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatrique vers les h\u00f4pitaux de district et les centres de sant\u00e9 primaire dans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es\",\"datePublished\":\"2024-03-22T10:24:04+00:00\",\"dateModified\":\"2024-03-22T11:15:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/\"},\"wordCount\":778,\"image\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/TB-Speed-Decentralization-Study_fr_vignette.jpg\",\"articleSection\":[\"Presse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/\",\"name\":\"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatrique vers les h\u00f4pitaux de district et les centres de sant\u00e9 primaire dans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es | Bordeaux population health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/TB-Speed-Decentralization-Study_fr_vignette.jpg\",\"datePublished\":\"2024-03-22T10:24:04+00:00\",\"dateModified\":\"2024-03-22T11:15:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/f2fdc07742e044bb0a3193dc1f103183\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/TB-Speed-Decentralization-Study_fr_vignette.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/TB-Speed-Decentralization-Study_fr_vignette.jpg\",\"width\":819,\"height\":443},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#website\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/\",\"name\":\"Bordeaux population health\",\"description\":\"Centre de recherche situ\u00e9 \u00e0 Bordeaux\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/f2fdc07742e044bb0a3193dc1f103183\",\"name\":\"Nicolas Koskas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c571fab758742e9c2609ac88a770e599997498e8ea60ee5d74f8550f0a8a9a0c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c571fab758742e9c2609ac88a770e599997498e8ea60ee5d74f8550f0a8a9a0c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c571fab758742e9c2609ac88a770e599997498e8ea60ee5d74f8550f0a8a9a0c?s=96&d=mm&r=g\",\"caption\":\"Nicolas Koskas\"},\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/author\\\/admin_bph\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es | Bordeaux population health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/","og_locale":"fr_FR","og_type":"article","og_title":"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es | Bordeaux population health","og_description":"D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es Deux \u00e9valuations issues d&rsquo;une \u00e9tude portant sur la d\u00e9centralisation du diagnostic de la tuberculose de l\u2019enfant dans les h\u00f4pitaux de district et les centres de sant\u00e9 primaire [&hellip;]","og_url":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/","og_site_name":"Bordeaux population health","article_published_time":"2024-03-22T10:24:04+00:00","article_modified_time":"2024-03-22T11:15:26+00:00","og_image":[{"width":819,"height":443,"url":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed-Decentralization-Study_fr_vignette.jpg","type":"image\/jpeg"}],"author":"Nicolas Koskas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nicolas Koskas","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/#article","isPartOf":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/"},"author":{"name":"Nicolas Koskas","@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/f2fdc07742e044bb0a3193dc1f103183"},"headline":"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatrique vers les h\u00f4pitaux de district et les centres de sant\u00e9 primaire dans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es","datePublished":"2024-03-22T10:24:04+00:00","dateModified":"2024-03-22T11:15:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/"},"wordCount":778,"image":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed-Decentralization-Study_fr_vignette.jpg","articleSection":["Presse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/","url":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/","name":"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatrique vers les h\u00f4pitaux de district et les centres de sant\u00e9 primaire dans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es | Bordeaux population health","isPartOf":{"@id":"https:\/\/www.bordeaux-population-health.center\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/#primaryimage"},"image":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed-Decentralization-Study_fr_vignette.jpg","datePublished":"2024-03-22T10:24:04+00:00","dateModified":"2024-03-22T11:15:26+00:00","author":{"@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/f2fdc07742e044bb0a3193dc1f103183"},"breadcrumb":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/#primaryimage","url":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed-Decentralization-Study_fr_vignette.jpg","contentUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/03\/TB-Speed-Decentralization-Study_fr_vignette.jpg","width":819,"height":443},{"@type":"BreadcrumbList","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/press-release-decentralising-the-diagnosis-of-childhood-tuberculosis-to-district-hospitals-and-primary-health-centres-in-high-tuberculosis-incidence-and-resource-limited-countries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bordeaux-population-health.center\/fr\/"},{"@type":"ListItem","position":2,"name":"COMMUNIQUE DE PRESSE: D\u00e9centralisation du diagnostic de la tuberculose p\u00e9diatriquevers les h\u00f4pitaux de district et les centres de sant\u00e9 primairedans les pays \u00e0 forte incidence de tuberculose et \u00e0 ressources limit\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.bordeaux-population-health.center\/#website","url":"https:\/\/www.bordeaux-population-health.center\/","name":"Bordeaux population health","description":"Centre de recherche situ\u00e9 \u00e0 Bordeaux","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bordeaux-population-health.center\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/f2fdc07742e044bb0a3193dc1f103183","name":"Nicolas Koskas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c571fab758742e9c2609ac88a770e599997498e8ea60ee5d74f8550f0a8a9a0c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c571fab758742e9c2609ac88a770e599997498e8ea60ee5d74f8550f0a8a9a0c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c571fab758742e9c2609ac88a770e599997498e8ea60ee5d74f8550f0a8a9a0c?s=96&d=mm&r=g","caption":"Nicolas Koskas"},"url":"https:\/\/www.bordeaux-population-health.center\/fr\/author\/admin_bph\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/6171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/users\/613"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/comments?post=6171"}],"version-history":[{"count":10,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/6171\/revisions"}],"predecessor-version":[{"id":6189,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/6171\/revisions\/6189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/media\/6157"}],"wp:attachment":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/media?parent=6171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/categories?post=6171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/tags?post=6171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}