{"id":13239,"date":"2026-02-09T14:45:45","date_gmt":"2026-02-09T13:45:45","guid":{"rendered":"https:\/\/www.bordeaux-population-health.center\/?p=13239"},"modified":"2026-02-13T09:11:46","modified_gmt":"2026-02-13T08:11:46","slug":"cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2","status":"publish","type":"post","link":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/","title":{"rendered":"Cycle de conf\u00e9rences \u00ab\u00a0Anthropologie et sant\u00e9 publique : quel futur commun ?\u00a0\u00bb"},"content":{"rendered":"<h2>L\u2019\u00e9quipe BPH-PHARes collabore avec ses partenaires de la Facult\u00e9 d\u2019<span id=\"DWT14209\" class=\"ZmSearchResult\"><span id=\"DWT14213\" class=\"ZmSearchResult\">Anthropologie de l\u2019universit\u00e9 de Bordeaux<\/span><\/span>\u00a0pour un cycle de conf\u00e9rences \u00e0 la crois\u00e9e de l\u2019<span id=\"DWT14211\" class=\"ZmSearchResult\"><span id=\"DWT14215\" class=\"ZmSearchResult\">anthropologie<\/span><\/span>\u00a0et de la sant\u00e9 publique.<\/h2>\n<h2>5 s\u00e9ances sont pr\u00e9vues de novembre 2025 \u00e0 mai 2026 entre les campus sant\u00e9 de Carreire et sciences humaines et sociales de la Victoire pour aborder les apports mutuels de ces deux disciplines et le croisement de leurs perspectives.<\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/cycle-anthropologie-fr\/\" rel=\"attachment wp-att-13334\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-13334 size-large\" src=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr-724x1024.jpg\" alt=\"\" width=\"724\" height=\"1024\" srcset=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr-724x1024.jpg 724w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr-212x300.jpg 212w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr-768x1086.jpg 768w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr-1086x1536.jpg 1086w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr-1448x2048.jpg 1448w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr.jpg 1587w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>Troisi\u00e8me s\u00e9ance : Cycle de conf\u00e9rences Anthropologie et sant\u00e9 publique : quel futur commun ?<\/h2>\n<p>Voir <strong>plus d&rsquo;information<\/strong> : <a href=\"https:\/\/lnkd.in\/eYPk9ES7\">https:\/\/lnkd.in\/eYPk9ES7<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Comit\u00e9 d\u2019organisation : Fiona Gedeon Achi, Carole Dufouil, Isabelle Gobatto, Andja Srebro<\/strong><br \/>\n<strong>avec l\u2019appui de Marie Manganelli, Nidhi Priya et Elyssa Sillam-Hyjazi<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Ouvert \u00e0 tous, en pr\u00e9sentiel<\/p>\n<p style=\"text-align: center;\"><strong>\ud83d\udcc5 Jeudi 26 f\u00e9vrier 2026 \u00e0 16h30 \u2013 18h00<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\ud83d\udccd Amphi Louis \u2013 ISPED \u2013 Campus Carreire<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Une s\u00e9rie de 5 conf\u00e9rences qui\u00a0 proposent une double probl\u00e9matique r\u00e9sum\u00e9e ici sous une forme volontairement provocatrice<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Comment l\u2019anthropologie peut-elle \u00eatre utile \u00e0 la pratique de la sant\u00e9 publique ?<\/li>\n<li>Et inversement, comment la sant\u00e9 publique peut-elle \u00eatre utile \u00e0 la pratique de l\u2019anthropologie tourn\u00e9e vers le registre de la sant\u00e9, dans son sens le plus large ?<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Cette nouvelle initiative doit son origine \u00e0<strong>\u00a0trois postulats<\/strong>\u00a0 :<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>Le premier est que, bien que les anthropologues de la sant\u00e9 et les sp\u00e9cialistes de sant\u00e9 publique sont expos\u00e9.es \u00e0 des pratiques et des contraintes professionnelles diff\u00e9rentes, ils et elles sont anim\u00e9.es par un objectif g\u00e9n\u00e9ral commun : appr\u00e9hender la sant\u00e9 et le bien-\u00eatre des individus. Si cet objectif est commun, son d\u00e9ploiement en questions de recherche et en pratiques de terrain diverge.<\/p>\n<p>Le deuxi\u00e8me postulat, corr\u00e9l\u00e9, est que, m\u00eame si on s\u2019accorde sur un objectif commun, de multiples visions et imaginations se cachent derri\u00e8re les termes qui composent cet objectif \u2013 par exemple, qu\u2019est-ce que la sant\u00e9 ? Que veut dire promouvoir la sant\u00e9 ?<\/p>\n<p>Le dernier postulat est que les \u00e9changes entre anthropologues et professionnels de la sant\u00e9 publique m\u00e9ritent d\u2019\u00eatre renforc\u00e9s pour pouvoir trouver des ponts communs entre objectifs et moyens, imagination et action. Cela requiert une capacit\u00e9 d\u2019\u00e9coute \u2013 mais aussi de traduction \u2013 respective, que ce s\u00e9minaire souhaite encourager.<\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p>Chaque session sera structur\u00e9e autour d\u2019un dialogue entre un anthropologue et un.e chercheur.e en sant\u00e9 publique pour favoriser une r\u00e9flexion collective, en posant les questions suivantes :<\/p>\n<p>\u2022 Qu\u2019est-ce cela veut dire d\u2019\u00eatre utile (\u00e0 la sant\u00e9 publique pour l\u2019anthropologie, \u00e0 l\u2019anthropologie pour la sant\u00e9 publique) ?<\/p>\n<p>\u2022 En quoi les recherches anthropologiques peuvent-elles guider la pratique des professionnels de sant\u00e9 ?<\/p>\n<p>\u2022 R\u00e9ciproquement, comment les anthropologues peuvent-ils int\u00e9grer les pr\u00e9occupations des professionnels de sant\u00e9 publique pour construire leurs enqu\u00eates et rendre leurs travaux accessibles, \u00ab pertinents \u00bb et entendus ?<\/p>\n<p>\u2022 Dans ce processus dynamique d\u2019interaction, quelle d\u00e9finition et quels objectifs de la \u00ab sant\u00e9 publique \u00bb \u00e9mergent ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9quipe BPH-PHARes collabore avec ses partenaires de la Facult\u00e9 d\u2019Anthropologie de l\u2019universit\u00e9 de Bordeaux\u00a0pour un cycle de conf\u00e9rences \u00e0 la crois\u00e9e de l\u2019anthropologie\u00a0et de la sant\u00e9 publique. 5 s\u00e9ances sont pr\u00e9vues de novembre 2025 \u00e0 mai 2026 entre les campus sant\u00e9 de Carreire et sciences humaines et sociales de la Victoire pour aborder les apports [&hellip;]<\/p>\n","protected":false},"author":913,"featured_media":13334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-13239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seminaires"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cycle de conf\u00e9rences &quot;Anthropologie et sant\u00e9 publique : quel futur commun ?&quot; | Bordeaux population health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cycle de conf\u00e9rences &quot;Anthropologie et sant\u00e9 publique : quel futur commun ?&quot; | Bordeaux population health\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9quipe BPH-PHARes collabore avec ses partenaires de la Facult\u00e9 d\u2019Anthropologie de l\u2019universit\u00e9 de Bordeaux\u00a0pour un cycle de conf\u00e9rences \u00e0 la crois\u00e9e de l\u2019anthropologie\u00a0et de la sant\u00e9 publique. 5 s\u00e9ances sont pr\u00e9vues de novembre 2025 \u00e0 mai 2026 entre les campus sant\u00e9 de Carreire et sciences humaines et sociales de la Victoire pour aborder les apports [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Bordeaux population health\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-09T13:45:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-13T08:11:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1587\" \/>\n\t<meta property=\"og:image:height\" content=\"2245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_PHARES\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_PHARES\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/\"},\"author\":{\"name\":\"admin_PHARES\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\"},\"headline\":\"Cycle de conf\u00e9rences \u00ab\u00a0Anthropologie et sant\u00e9 publique : quel futur commun ?\u00a0\u00bb\",\"datePublished\":\"2026-02-09T13:45:45+00:00\",\"dateModified\":\"2026-02-13T08:11:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/\"},\"wordCount\":504,\"image\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Cycle-Anthropologie-fr.jpg\",\"articleSection\":[\"S\u00e9minaires\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/\",\"name\":\"Cycle de conf\u00e9rences \\\"Anthropologie et sant\u00e9 publique : quel futur commun ?\\\" | Bordeaux population health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Cycle-Anthropologie-fr.jpg\",\"datePublished\":\"2026-02-09T13:45:45+00:00\",\"dateModified\":\"2026-02-13T08:11:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Cycle-Anthropologie-fr.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Cycle-Anthropologie-fr.jpg\",\"width\":1587,\"height\":2245},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cycle de conf\u00e9rences &#8220;Anthropologie et sant\u00e9 publique : quel futur commun ?&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#website\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/\",\"name\":\"Bordeaux population health\",\"description\":\"Centre de recherche situ\u00e9 \u00e0 Bordeaux\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\",\"name\":\"admin_PHARES\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"caption\":\"admin_PHARES\"},\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/author\\\/admin_phares\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cycle de conf\u00e9rences \"Anthropologie et sant\u00e9 publique : quel futur commun ?\" | Bordeaux population health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Cycle de conf\u00e9rences \"Anthropologie et sant\u00e9 publique : quel futur commun ?\" | Bordeaux population health","og_description":"L\u2019\u00e9quipe BPH-PHARes collabore avec ses partenaires de la Facult\u00e9 d\u2019Anthropologie de l\u2019universit\u00e9 de Bordeaux\u00a0pour un cycle de conf\u00e9rences \u00e0 la crois\u00e9e de l\u2019anthropologie\u00a0et de la sant\u00e9 publique. 5 s\u00e9ances sont pr\u00e9vues de novembre 2025 \u00e0 mai 2026 entre les campus sant\u00e9 de Carreire et sciences humaines et sociales de la Victoire pour aborder les apports [&hellip;]","og_url":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/","og_site_name":"Bordeaux population health","article_published_time":"2026-02-09T13:45:45+00:00","article_modified_time":"2026-02-13T08:11:46+00:00","og_image":[{"width":1587,"height":2245,"url":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr.jpg","type":"image\/jpeg"}],"author":"admin_PHARES","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin_PHARES","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/#article","isPartOf":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/"},"author":{"name":"admin_PHARES","@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f"},"headline":"Cycle de conf\u00e9rences \u00ab\u00a0Anthropologie et sant\u00e9 publique : quel futur commun ?\u00a0\u00bb","datePublished":"2026-02-09T13:45:45+00:00","dateModified":"2026-02-13T08:11:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/"},"wordCount":504,"image":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr.jpg","articleSection":["S\u00e9minaires"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/","url":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/","name":"Cycle de conf\u00e9rences \"Anthropologie et sant\u00e9 publique : quel futur commun ?\" | Bordeaux population health","isPartOf":{"@id":"https:\/\/www.bordeaux-population-health.center\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/#primaryimage"},"image":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr.jpg","datePublished":"2026-02-09T13:45:45+00:00","dateModified":"2026-02-13T08:11:46+00:00","author":{"@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f"},"breadcrumb":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/#primaryimage","url":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr.jpg","contentUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2026\/02\/Cycle-Anthropologie-fr.jpg","width":1587,"height":2245},{"@type":"BreadcrumbList","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/cycle-de-conferences-anthropologie-et-sante-publique-quel-futur-commun-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bordeaux-population-health.center\/fr\/"},{"@type":"ListItem","position":2,"name":"Cycle de conf\u00e9rences &#8220;Anthropologie et sant\u00e9 publique : quel futur commun ?&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.bordeaux-population-health.center\/#website","url":"https:\/\/www.bordeaux-population-health.center\/","name":"Bordeaux population health","description":"Centre de recherche situ\u00e9 \u00e0 Bordeaux","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bordeaux-population-health.center\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f","name":"admin_PHARES","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","caption":"admin_PHARES"},"url":"https:\/\/www.bordeaux-population-health.center\/fr\/author\/admin_phares\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/13239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/users\/913"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/comments?post=13239"}],"version-history":[{"count":8,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/13239\/revisions"}],"predecessor-version":[{"id":13339,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/13239\/revisions\/13339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/media\/13334"}],"wp:attachment":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/media?parent=13239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/categories?post=13239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/tags?post=13239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}