{"id":11564,"date":"2025-09-17T16:12:13","date_gmt":"2025-09-17T14:12:13","guid":{"rendered":"https:\/\/www.bordeaux-population-health.center\/?p=11564"},"modified":"2026-02-05T09:47:22","modified_gmt":"2026-02-05T08:47:22","slug":"souutenance-de-these-marie-tartaglia","status":"publish","type":"post","link":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/","title":{"rendered":"SOUUTENANCE DE THESE : MARIE TARTAGLIA"},"content":{"rendered":"<p><strong>Marie TARTAGLIA<\/strong> soutient sa th\u00e8se en sant\u00e9 publique &#8211; option \u00e9pid\u00e9miologie r\u00e9alis\u00e9e sous la direction du <strong>Dr. Fleur DELVA<\/strong> et <strong>Pr. Ronan GARLANTEZEC<\/strong> intitul\u00e9e :<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>\u00ab\u00a0Multi-expositions professionnelles maternelles <\/strong><strong>durant la grossesse et croissance f\u0153tale\u00a0\u00bb<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-11565 size-large\" src=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/09\/Aff.-M.-TARTAGLIA-20250929-724x1024.jpg\" alt=\"\" width=\"724\" height=\"1024\" srcset=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/09\/Aff.-M.-TARTAGLIA-20250929-724x1024.jpg 724w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/09\/Aff.-M.-TARTAGLIA-20250929-212x300.jpg 212w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/09\/Aff.-M.-TARTAGLIA-20250929-768x1086.jpg 768w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/09\/Aff.-M.-TARTAGLIA-20250929-1086x1536.jpg 1086w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/09\/Aff.-M.-TARTAGLIA-20250929-1448x2048.jpg 1448w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/09\/Aff.-M.-TARTAGLIA-20250929.jpg 1587w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La soutenance (en fran\u00e7ais) se tiendra le :<\/p>\n<p><strong>Lundi 29 septembre 2025 \u00e0 15h<\/strong><\/p>\n<p>Lieu : Amphi Louis &#8211; ISPED &#8211; Bordeaux<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marie TARTAGLIA soutient sa th\u00e8se en sant\u00e9 publique &#8211; option \u00e9pid\u00e9miologie r\u00e9alis\u00e9e sous la direction du Dr. Fleur DELVA et Pr. Ronan GARLANTEZEC intitul\u00e9e : &nbsp; \u00ab\u00a0Multi-expositions professionnelles maternelles durant la grossesse et croissance f\u0153tale\u00a0\u00bb &nbsp; &nbsp; &nbsp; La soutenance (en fran\u00e7ais) se tiendra le : Lundi 29 septembre 2025 \u00e0 15h Lieu : Amphi [&hellip;]<\/p>\n","protected":false},"author":913,"featured_media":7747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58],"tags":[],"class_list":["post-11564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SOUUTENANCE DE THESE : MARIE TARTAGLIA | Bordeaux population health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOUUTENANCE DE THESE : MARIE TARTAGLIA | Bordeaux population health\" \/>\n<meta property=\"og:description\" content=\"Marie TARTAGLIA soutient sa th\u00e8se en sant\u00e9 publique &#8211; option \u00e9pid\u00e9miologie r\u00e9alis\u00e9e sous la direction du Dr. Fleur DELVA et Pr. Ronan GARLANTEZEC intitul\u00e9e : &nbsp; \u00ab\u00a0Multi-expositions professionnelles maternelles durant la grossesse et croissance f\u0153tale\u00a0\u00bb &nbsp; &nbsp; &nbsp; La soutenance (en fran\u00e7ais) se tiendra le : Lundi 29 septembre 2025 \u00e0 15h Lieu : Amphi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/\" \/>\n<meta property=\"og:site_name\" content=\"Bordeaux population health\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T14:12:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T08:47:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/09\/Bandeau-soutenances2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"819\" \/>\n\t<meta property=\"og:image:height\" content=\"443\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin_PHARES\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_PHARES\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/\"},\"author\":{\"name\":\"admin_PHARES\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\"},\"headline\":\"SOUUTENANCE DE THESE : MARIE TARTAGLIA\",\"datePublished\":\"2025-09-17T14:12:13+00:00\",\"dateModified\":\"2026-02-05T08:47:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/\"},\"wordCount\":66,\"image\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Bandeau-soutenances2.png\",\"articleSection\":[\"Ev\u00e8nement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/\",\"name\":\"SOUUTENANCE DE THESE : MARIE TARTAGLIA | Bordeaux population health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Bandeau-soutenances2.png\",\"datePublished\":\"2025-09-17T14:12:13+00:00\",\"dateModified\":\"2026-02-05T08:47:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Bandeau-soutenances2.png\",\"contentUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Bandeau-soutenances2.png\",\"width\":819,\"height\":443},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/souutenance-de-these-marie-tartaglia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOUUTENANCE DE THESE : MARIE TARTAGLIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#website\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/\",\"name\":\"Bordeaux population health\",\"description\":\"Centre de recherche situ\u00e9 \u00e0 Bordeaux\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\",\"name\":\"admin_PHARES\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"caption\":\"admin_PHARES\"},\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/author\\\/admin_phares\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SOUUTENANCE DE THESE : MARIE TARTAGLIA | Bordeaux population health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/","og_locale":"fr_FR","og_type":"article","og_title":"SOUUTENANCE DE THESE : MARIE TARTAGLIA | Bordeaux population health","og_description":"Marie TARTAGLIA soutient sa th\u00e8se en sant\u00e9 publique &#8211; option \u00e9pid\u00e9miologie r\u00e9alis\u00e9e sous la direction du Dr. Fleur DELVA et Pr. Ronan GARLANTEZEC intitul\u00e9e : &nbsp; \u00ab\u00a0Multi-expositions professionnelles maternelles durant la grossesse et croissance f\u0153tale\u00a0\u00bb &nbsp; &nbsp; &nbsp; La soutenance (en fran\u00e7ais) se tiendra le : Lundi 29 septembre 2025 \u00e0 15h Lieu : Amphi [&hellip;]","og_url":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/","og_site_name":"Bordeaux population health","article_published_time":"2025-09-17T14:12:13+00:00","article_modified_time":"2026-02-05T08:47:22+00:00","og_image":[{"width":819,"height":443,"url":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/09\/Bandeau-soutenances2.png","type":"image\/png"}],"author":"admin_PHARES","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin_PHARES","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/#article","isPartOf":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/"},"author":{"name":"admin_PHARES","@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f"},"headline":"SOUUTENANCE DE THESE : MARIE TARTAGLIA","datePublished":"2025-09-17T14:12:13+00:00","dateModified":"2026-02-05T08:47:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/"},"wordCount":66,"image":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/09\/Bandeau-soutenances2.png","articleSection":["Ev\u00e8nement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/","url":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/","name":"SOUUTENANCE DE THESE : MARIE TARTAGLIA | Bordeaux population health","isPartOf":{"@id":"https:\/\/www.bordeaux-population-health.center\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/#primaryimage"},"image":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/09\/Bandeau-soutenances2.png","datePublished":"2025-09-17T14:12:13+00:00","dateModified":"2026-02-05T08:47:22+00:00","author":{"@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f"},"breadcrumb":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/#primaryimage","url":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/09\/Bandeau-soutenances2.png","contentUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/09\/Bandeau-soutenances2.png","width":819,"height":443},{"@type":"BreadcrumbList","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/souutenance-de-these-marie-tartaglia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bordeaux-population-health.center\/fr\/"},{"@type":"ListItem","position":2,"name":"SOUUTENANCE DE THESE : MARIE TARTAGLIA"}]},{"@type":"WebSite","@id":"https:\/\/www.bordeaux-population-health.center\/#website","url":"https:\/\/www.bordeaux-population-health.center\/","name":"Bordeaux population health","description":"Centre de recherche situ\u00e9 \u00e0 Bordeaux","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bordeaux-population-health.center\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f","name":"admin_PHARES","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","caption":"admin_PHARES"},"url":"https:\/\/www.bordeaux-population-health.center\/fr\/author\/admin_phares\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/11564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/users\/913"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/comments?post=11564"}],"version-history":[{"count":2,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/11564\/revisions"}],"predecessor-version":[{"id":11569,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/11564\/revisions\/11569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/media\/7747"}],"wp:attachment":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/media?parent=11564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/categories?post=11564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/tags?post=11564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}