{"id":10119,"date":"2025-04-09T09:53:39","date_gmt":"2025-04-09T07:53:39","guid":{"rendered":"https:\/\/www.bordeaux-population-health.center\/?p=10119"},"modified":"2026-02-05T08:53:29","modified_gmt":"2026-02-05T07:53:29","slug":"association-bbph","status":"publish","type":"post","link":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/","title":{"rendered":"S\u00e9minaire de l&rsquo;association BBPH &lsquo;Bien s&rsquo;informer en sant\u00e9 publique&rsquo;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3585 size-full\" src=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2023\/05\/BBPH.png\" alt=\"\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2023\/05\/BBPH.png 500w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2023\/05\/BBPH-300x300.png 300w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2023\/05\/BBPH-150x150.png 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><\/h1>\n<h1 style=\"text-align: center;\"><strong>L&rsquo;association BBPH vous invite \u00e0 un s\u00e9minaire ouvert \u00e0 toutes et tous, pour r\u00e9fl\u00e9chir ensemble \u00e0 ces enjeux essentiels.<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><\/h1>\n<h1 style=\"text-align: center;\">L<strong>\u2019inscription est facultative,<\/strong> mais elle nous aide \u00e0 anticiper le nombre de participant\u00b7es :<\/h1>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10564 size-large\" src=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/04\/Mieux-sinformer-en-Sante-Publique-Enjeux-et-Bonnes-Pratiques_compressed-777x1024.jpg\" alt=\"\" width=\"777\" height=\"1024\" srcset=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/04\/Mieux-sinformer-en-Sante-Publique-Enjeux-et-Bonnes-Pratiques_compressed-777x1024.jpg 777w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/04\/Mieux-sinformer-en-Sante-Publique-Enjeux-et-Bonnes-Pratiques_compressed-228x300.jpg 228w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/04\/Mieux-sinformer-en-Sante-Publique-Enjeux-et-Bonnes-Pratiques_compressed-768x1012.jpg 768w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/04\/Mieux-sinformer-en-Sante-Publique-Enjeux-et-Bonnes-Pratiques_compressed-1166x1536.jpg 1166w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/04\/Mieux-sinformer-en-Sante-Publique-Enjeux-et-Bonnes-Pratiques_compressed-1554x2048.jpg 1554w, https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2025\/04\/Mieux-sinformer-en-Sante-Publique-Enjeux-et-Bonnes-Pratiques_compressed-scaled.jpg 1943w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><\/p>\n<div><\/div>\n<div><\/div>\n<h2><\/h2>\n<h2 style=\"text-align: center;\"><strong>Venez nombreuses et nombreux !<\/strong><\/h2>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><\/h2>\n<h2 style=\"text-align: center;\"><strong>O\u00f9 et quand ?<\/strong><\/h2>\n<h2 style=\"text-align: center;\"><\/h2>\n<div>\n<h2 style=\"text-align: center;\"><span id=\"OBJ_PREFIX_DWT1220_com_zimbra_date\" class=\"Object\" role=\"link\">Mardi 13 mai 2025<\/span><br \/>\n13h00 \u2013 14h30<br \/>\nB\u00e2timent ED salle 28<\/h2>\n<\/div>\n<\/div>\n<h2 style=\"text-align: center;\"><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div>\n<div>\n<h2 style=\"text-align: center;\">Avec deux intervenantes expertes :<\/h2>\n<\/div>\n<\/div>\n<h2 style=\"text-align: center;\"><\/h2>\n<p>*<\/p>\n<div>\n<div>\n<h2 style=\"text-align: center;\"><strong><span id=\"OBJ_PREFIX_DWT1222_com_zimbra_url\" class=\"Object\" role=\"link\"><a href=\"https:\/\/www.linkedin.com\/in\/genevi%C3%A8ve-ch%C3%AAne\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Genevi\u00e8ve Ch\u00eane<\/a><\/span>,<\/strong> professeure de biostatistiques et sant\u00e9 publique (ISPED &amp; BPH) :<\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><strong>&gt; Indicateurs de sant\u00e9 : d\u00e9m\u00ealer le vrai du flou<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><strong><span id=\"OBJ_PREFIX_DWT1224_com_zimbra_url\" class=\"Object\" role=\"link\"><a href=\"https:\/\/www.linkedin.com\/in\/priscille-riviere-90751b1a\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Priscille Riviere<\/a><\/span>,<\/strong> directrice adjointe de la communication \u00e0 l\u2019Inserm :<\/h2>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><strong>&gt; Lutte contre la d\u00e9sinformation et les fake-news en sant\u00e9<\/strong><\/h2>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; L&rsquo;association BBPH vous invite \u00e0 un s\u00e9minaire ouvert \u00e0 toutes et tous, pour r\u00e9fl\u00e9chir ensemble \u00e0 ces enjeux essentiels. &nbsp; &nbsp; &nbsp; L\u2019inscription est facultative, mais elle nous aide \u00e0 anticiper le nombre de participant\u00b7es : Venez nombreuses et nombreux ! &nbsp; O\u00f9 et quand ? Mardi 13 mai 2025 13h00 \u2013 14h30 B\u00e2timent [&hellip;]<\/p>\n","protected":false},"author":913,"featured_media":8151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58],"tags":[],"class_list":["post-10119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9minaire de l&#039;association BBPH &#039;Bien s&#039;informer en sant\u00e9 publique&#039; | Bordeaux population health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9minaire de l&#039;association BBPH &#039;Bien s&#039;informer en sant\u00e9 publique&#039; | Bordeaux population health\" \/>\n<meta property=\"og:description\" content=\"&nbsp; L&rsquo;association BBPH vous invite \u00e0 un s\u00e9minaire ouvert \u00e0 toutes et tous, pour r\u00e9fl\u00e9chir ensemble \u00e0 ces enjeux essentiels. &nbsp; &nbsp; &nbsp; L\u2019inscription est facultative, mais elle nous aide \u00e0 anticiper le nombre de participant\u00b7es : Venez nombreuses et nombreux ! &nbsp; O\u00f9 et quand ? Mardi 13 mai 2025 13h00 \u2013 14h30 B\u00e2timent [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/\" \/>\n<meta property=\"og:site_name\" content=\"Bordeaux population health\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T07:53:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T07:53:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/11\/Bandeau-BBPH-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1587\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin_PHARES\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_PHARES\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/\"},\"author\":{\"name\":\"admin_PHARES\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\"},\"headline\":\"S\u00e9minaire de l&rsquo;association BBPH &lsquo;Bien s&rsquo;informer en sant\u00e9 publique&rsquo;\",\"datePublished\":\"2025-04-09T07:53:39+00:00\",\"dateModified\":\"2026-02-05T07:53:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/\"},\"wordCount\":120,\"image\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Bandeau-BBPH-1.jpg\",\"articleSection\":[\"Ev\u00e8nement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/\",\"name\":\"S\u00e9minaire de l'association BBPH 'Bien s'informer en sant\u00e9 publique' | Bordeaux population health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Bandeau-BBPH-1.jpg\",\"datePublished\":\"2025-04-09T07:53:39+00:00\",\"dateModified\":\"2026-02-05T07:53:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Bandeau-BBPH-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Bandeau-BBPH-1.jpg\",\"width\":1587,\"height\":767,\"caption\":\"Copie de Affiches th\u00e8ses - 4\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/association-bbph\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9minaire de l&#8217;association BBPH &#8216;Bien s&#8217;informer en sant\u00e9 publique&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#website\",\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/\",\"name\":\"Bordeaux population health\",\"description\":\"Centre de recherche situ\u00e9 \u00e0 Bordeaux\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/#\\\/schema\\\/person\\\/8e2d46eae7f310ed66ee11ea11e03b3f\",\"name\":\"admin_PHARES\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g\",\"caption\":\"admin_PHARES\"},\"url\":\"https:\\\/\\\/www.bordeaux-population-health.center\\\/fr\\\/author\\\/admin_phares\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9minaire de l'association BBPH 'Bien s'informer en sant\u00e9 publique' | Bordeaux population health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9minaire de l'association BBPH 'Bien s'informer en sant\u00e9 publique' | Bordeaux population health","og_description":"&nbsp; L&rsquo;association BBPH vous invite \u00e0 un s\u00e9minaire ouvert \u00e0 toutes et tous, pour r\u00e9fl\u00e9chir ensemble \u00e0 ces enjeux essentiels. &nbsp; &nbsp; &nbsp; L\u2019inscription est facultative, mais elle nous aide \u00e0 anticiper le nombre de participant\u00b7es : Venez nombreuses et nombreux ! &nbsp; O\u00f9 et quand ? Mardi 13 mai 2025 13h00 \u2013 14h30 B\u00e2timent [&hellip;]","og_url":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/","og_site_name":"Bordeaux population health","article_published_time":"2025-04-09T07:53:39+00:00","article_modified_time":"2026-02-05T07:53:29+00:00","og_image":[{"width":1587,"height":767,"url":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/11\/Bandeau-BBPH-1.jpg","type":"image\/jpeg"}],"author":"admin_PHARES","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin_PHARES","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/#article","isPartOf":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/"},"author":{"name":"admin_PHARES","@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f"},"headline":"S\u00e9minaire de l&rsquo;association BBPH &lsquo;Bien s&rsquo;informer en sant\u00e9 publique&rsquo;","datePublished":"2025-04-09T07:53:39+00:00","dateModified":"2026-02-05T07:53:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/"},"wordCount":120,"image":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/11\/Bandeau-BBPH-1.jpg","articleSection":["Ev\u00e8nement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/","url":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/","name":"S\u00e9minaire de l'association BBPH 'Bien s'informer en sant\u00e9 publique' | Bordeaux population health","isPartOf":{"@id":"https:\/\/www.bordeaux-population-health.center\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/#primaryimage"},"image":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/11\/Bandeau-BBPH-1.jpg","datePublished":"2025-04-09T07:53:39+00:00","dateModified":"2026-02-05T07:53:29+00:00","author":{"@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f"},"breadcrumb":{"@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/#primaryimage","url":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/11\/Bandeau-BBPH-1.jpg","contentUrl":"https:\/\/www.bordeaux-population-health.center\/wp-content\/uploads\/2024\/11\/Bandeau-BBPH-1.jpg","width":1587,"height":767,"caption":"Copie de Affiches th\u00e8ses - 4"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bordeaux-population-health.center\/fr\/association-bbph\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bordeaux-population-health.center\/fr\/"},{"@type":"ListItem","position":2,"name":"S\u00e9minaire de l&#8217;association BBPH &#8216;Bien s&#8217;informer en sant\u00e9 publique&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.bordeaux-population-health.center\/#website","url":"https:\/\/www.bordeaux-population-health.center\/","name":"Bordeaux population health","description":"Centre de recherche situ\u00e9 \u00e0 Bordeaux","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bordeaux-population-health.center\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.bordeaux-population-health.center\/#\/schema\/person\/8e2d46eae7f310ed66ee11ea11e03b3f","name":"admin_PHARES","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c8d6a42347391304251788c5fe2564f4ca9823349a0f0386ff8ca9849932df1?s=96&d=mm&r=g","caption":"admin_PHARES"},"url":"https:\/\/www.bordeaux-population-health.center\/fr\/author\/admin_phares\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/10119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/users\/913"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/comments?post=10119"}],"version-history":[{"count":20,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/10119\/revisions"}],"predecessor-version":[{"id":10597,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/posts\/10119\/revisions\/10597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/media\/8151"}],"wp:attachment":[{"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/media?parent=10119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/categories?post=10119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bordeaux-population-health.center\/fr\/wp-json\/wp\/v2\/tags?post=10119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}